{"id":6252,"date":"2021-03-12T09:31:38","date_gmt":"2021-03-12T08:31:38","guid":{"rendered":"https:\/\/gymnasium-nordenham.de\/?p=6252"},"modified":"2025-06-25T14:09:05","modified_gmt":"2025-06-25T12:09:05","slug":"rueckkehr-in-den-wechselunterricht-verzoegert-sich","status":"publish","type":"post","link":"https:\/\/gymnasium-nordenham.de\/en\/rueckkehr-in-den-wechselunterricht-verzoegert-sich","title":{"rendered":"R\u00fcckkehr in den Wechselunterricht verz\u00f6gert sich"},"content":{"rendered":"<div data-elementor-type=\"wp-post\" data-elementor-id=\"6252\" class=\"elementor elementor-6252\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-118ff95 elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"118ff95\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-34dc24d\" data-id=\"34dc24d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6ecfdf1 elementor-widget elementor-widget-heading\" data-id=\"6ecfdf1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-large\">Die Jahrg\u00e4nge 5 bis 7 sowie 12 m\u00fcssen vorerst noch Zuhause bleiben.<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ecde086 elementor-widget elementor-widget-image\" data-id=\"ecde086\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"640\" height=\"1\" src=\"https:\/\/gymnasium-nordenham.de\/wp-content\/uploads\/2020\/04\/spektrumani.gif\" class=\"attachment-large size-large wp-image-1204\" alt=\"\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-efa2c32 elementor-widget elementor-widget-text-editor\" data-id=\"efa2c32\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: justify;\"><span style=\"font-family: georgia, palatino, serif; font-size: 12pt;\">Obwohl eigentlich ab dem 15. M\u00e4rz wieder das Wechselmodell f\u00fcr die oben genannten Jahrg\u00e4nge gelten sollte, muss der Pr\u00e4senzunterricht vorerst noch verschoben werden. Grund daf\u00fcr ist der aktuell immer noch zu hohe Inzidenzwert im Landkreis. Solange der tagesaktuelle Wert \u00fcber 100 liegt, wird es auch an den folgenden drei Tagen keinen Unterricht in der Schule geben. Die einzige Ausnahme von dieser Regelung erf\u00e4hrt weiterhin nur der 13. Jahrgang.<\/span><\/p><p style=\"text-align: justify;\"><span style=\"font-family: georgia, palatino, serif; font-size: 12pt;\">Sobald der Inzidenzwert den Grenzwert unterschreitet und die Voraussetzungen f\u00fcr den Wechselunterricht vorliegen, werden wir dies \u00fcber die Homepage und \u00fcber IServ mitteilen. Solange bitten wir Sie, sich hinsichtlich der aktuellen Zahlen auf dem Laufenden zu halten und auch immer wieder mal auf unsere Homepage zu schauen.<\/span><\/p><p style=\"text-align: justify;\"><span style=\"font-family: georgia, palatino, serif; font-size: 12pt;\">Anschlie\u00dfend finden Sie noch zwei Links zu Internetseiten, die tagesaktuell den Inzidenzwert ver\u00f6ffentlichen:<\/span><\/p><p style=\"text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif; font-size: 12pt;\">Homepage des Landkreises<br \/><\/span><\/p><p style=\"text-align: justify;\"><span style=\"font-size: 12pt; font-family: arial, helvetica, sans-serif;\"><a href=\"https:\/\/www.niedersachsen.de\/Coronavirus\/aktuelle_lage_in_niedersachsen\/\" target=\"_blank\" rel=\"noopener\">Homepage des Landes<\/a><\/span> <\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-a2de6f4\" data-id=\"a2de6f4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8fba690 elementor-widget elementor-widget-heading\" data-id=\"8fba690\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Wichtiges im \u00dcberblick<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29b69af elementor-nav-menu__align-start elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"29b69af\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;vertical&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas e-plus-icon\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;&quot;},&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Menu\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-vertical e--pointer-none\">\n\t\t\t\t<ul id=\"menu-1-29b69af\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-5094\"><a href=\"https:\/\/gymnasium-nordenham.de\/en\/formulare-und-downloads\" class=\"elementor-item\">Formulare und Downloads<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-3155\"><a href=\"https:\/\/account.sams-on.de\/authentication\/login?instance=gym-nordenham\" class=\"elementor-item\">Mittagessen Online Bestellung<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-3156\"><a href=\"https:\/\/webuntis.com\/\" class=\"elementor-item\">Online Vertretungsplan<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-5054\"><a href=\"https:\/\/gymnasium-nordenham.de\/en\/kontakt\" class=\"elementor-item\">Kontakt<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Menu Toggle\" aria-expanded=\"false\">\n\t\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open eicon-menu-bar\"><\/i><i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close eicon-close\"><\/i>\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-29b69af\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-5094\"><a href=\"https:\/\/gymnasium-nordenham.de\/en\/formulare-und-downloads\" class=\"elementor-item\" tabindex=\"-1\">Formulare und Downloads<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-3155\"><a href=\"https:\/\/account.sams-on.de\/authentication\/login?instance=gym-nordenham\" class=\"elementor-item\" tabindex=\"-1\">Mittagessen Online Bestellung<\/a><\/li>\n<li class=\"menu-item menu-item-type-custom menu-item-object-custom menu-item-3156\"><a href=\"https:\/\/webuntis.com\/\" class=\"elementor-item\" tabindex=\"-1\">Online Vertretungsplan<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-5054\"><a href=\"https:\/\/gymnasium-nordenham.de\/en\/kontakt\" class=\"elementor-item\" tabindex=\"-1\">Kontakt<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4a9e18c elementor-nav-menu__align-start elementor-nav-menu--dropdown-tablet elementor-nav-menu__text-align-aside elementor-nav-menu--toggle elementor-nav-menu--burger elementor-widget elementor-widget-nav-menu\" data-id=\"4a9e18c\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;layout&quot;:&quot;vertical&quot;,&quot;submenu_icon&quot;:{&quot;value&quot;:&quot;&lt;i class=\\&quot;fas e-plus-icon\\&quot; aria-hidden=\\&quot;true\\&quot;&gt;&lt;\\\/i&gt;&quot;,&quot;library&quot;:&quot;&quot;},&quot;toggle&quot;:&quot;burger&quot;}\" data-widget_type=\"nav-menu.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t<nav aria-label=\"Menu\" class=\"elementor-nav-menu--main elementor-nav-menu__container elementor-nav-menu--layout-vertical e--pointer-none\">\n\t\t\t\t<ul id=\"menu-1-4a9e18c\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-5075\"><a href=\"https:\/\/gymnasium-nordenham.de\/en\/impressum-2\" class=\"elementor-item\">Impressum<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-5074\"><a href=\"https:\/\/gymnasium-nordenham.de\/en\/disclaimer-2\" class=\"elementor-item\">Disclaimer<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page current_page_parent menu-item-5031\"><a href=\"https:\/\/gymnasium-nordenham.de\/en\/archiv\" class=\"elementor-item\">Archiv<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t<div class=\"elementor-menu-toggle\" role=\"button\" tabindex=\"0\" aria-label=\"Menu Toggle\" aria-expanded=\"false\">\n\t\t\t<i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--open eicon-menu-bar\"><\/i><i aria-hidden=\"true\" role=\"presentation\" class=\"elementor-menu-toggle__icon--close eicon-close\"><\/i>\t\t<\/div>\n\t\t\t\t\t<nav class=\"elementor-nav-menu--dropdown elementor-nav-menu__container\" aria-hidden=\"true\">\n\t\t\t\t<ul id=\"menu-2-4a9e18c\" class=\"elementor-nav-menu sm-vertical\"><li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-5075\"><a href=\"https:\/\/gymnasium-nordenham.de\/en\/impressum-2\" class=\"elementor-item\" tabindex=\"-1\">Impressum<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page menu-item-5074\"><a href=\"https:\/\/gymnasium-nordenham.de\/en\/disclaimer-2\" class=\"elementor-item\" tabindex=\"-1\">Disclaimer<\/a><\/li>\n<li class=\"menu-item menu-item-type-post_type menu-item-object-page current_page_parent menu-item-5031\"><a href=\"https:\/\/gymnasium-nordenham.de\/en\/archiv\" class=\"elementor-item\" tabindex=\"-1\">Archiv<\/a><\/li>\n<\/ul>\t\t\t<\/nav>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Die Jahrg\u00e4nge 5 bis 7 sowie 12 m\u00fcssen vorerst noch Zuhause bleiben. Obwohl eigentlich ab dem 15. M\u00e4rz wieder das Wechselmodell f\u00fcr die oben genannten Jahrg\u00e4nge gelten sollte, muss der Pr\u00e4senzunterricht vorerst noch verschoben werden. Grund daf\u00fcr ist der aktuell &hellip; <a href=\"https:\/\/gymnasium-nordenham.de\/en\/rueckkehr-in-den-wechselunterricht-verzoegert-sich\">Continue reading <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"elementor_header_footer","format":"standard","meta":{"footnotes":""},"categories":[46,44,47,1],"tags":[],"class_list":["post-6252","post","type-post","status-publish","format-standard","hentry","category-corona","category-schul-news","category-schulausfall","category-uncategorized"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>R\u00fcckkehr in den Wechselunterricht verz\u00f6gert sich - Gymnasium Nordenham<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gymnasium-nordenham.de\/en\/rueckkehr-in-den-wechselunterricht-verzoegert-sich\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"R\u00fcckkehr in den Wechselunterricht verz\u00f6gert sich - Gymnasium Nordenham\" \/>\n<meta property=\"og:description\" content=\"Die Jahrg\u00e4nge 5 bis 7 sowie 12 m\u00fcssen vorerst noch Zuhause bleiben. Obwohl eigentlich ab dem 15. M\u00e4rz wieder das Wechselmodell f\u00fcr die oben genannten Jahrg\u00e4nge gelten sollte, muss der Pr\u00e4senzunterricht vorerst noch verschoben werden. Grund daf\u00fcr ist der aktuell &hellip; Continue reading &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gymnasium-nordenham.de\/en\/rueckkehr-in-den-wechselunterricht-verzoegert-sich\/\" \/>\n<meta property=\"og:site_name\" content=\"Gymnasium Nordenham\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-12T08:31:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-25T12:09:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gymnasium-nordenham.de\/wp-content\/uploads\/2020\/04\/spektrumani.gif\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"2\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/gif\" \/>\n<meta name=\"author\" content=\"Philipp Hetzel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Philipp Hetzel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimated reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gymnasium-nordenham.de\\\/rueckkehr-in-den-wechselunterricht-verzoegert-sich#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gymnasium-nordenham.de\\\/rueckkehr-in-den-wechselunterricht-verzoegert-sich\"},\"author\":{\"name\":\"Philipp Hetzel\",\"@id\":\"https:\\\/\\\/gymnasium-nordenham.de\\\/#\\\/schema\\\/person\\\/1e6d811f9e37c192d07e964e5f6a66f6\"},\"headline\":\"R\u00fcckkehr in den Wechselunterricht verz\u00f6gert sich\",\"datePublished\":\"2021-03-12T08:31:38+00:00\",\"dateModified\":\"2025-06-25T12:09:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gymnasium-nordenham.de\\\/rueckkehr-in-den-wechselunterricht-verzoegert-sich\"},\"wordCount\":162,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/gymnasium-nordenham.de\\\/rueckkehr-in-den-wechselunterricht-verzoegert-sich#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gymnasium-nordenham.de\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/spektrumani.gif\",\"articleSection\":[\"Corona\",\"Schul-News\",\"Schulausfall\",\"Uncategorized\"],\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/gymnasium-nordenham.de\\\/rueckkehr-in-den-wechselunterricht-verzoegert-sich#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gymnasium-nordenham.de\\\/rueckkehr-in-den-wechselunterricht-verzoegert-sich\",\"url\":\"https:\\\/\\\/gymnasium-nordenham.de\\\/rueckkehr-in-den-wechselunterricht-verzoegert-sich\",\"name\":\"R\u00fcckkehr in den Wechselunterricht verz\u00f6gert sich - Gymnasium Nordenham\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gymnasium-nordenham.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gymnasium-nordenham.de\\\/rueckkehr-in-den-wechselunterricht-verzoegert-sich#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gymnasium-nordenham.de\\\/rueckkehr-in-den-wechselunterricht-verzoegert-sich#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gymnasium-nordenham.de\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/spektrumani.gif\",\"datePublished\":\"2021-03-12T08:31:38+00:00\",\"dateModified\":\"2025-06-25T12:09:05+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/gymnasium-nordenham.de\\\/#\\\/schema\\\/person\\\/1e6d811f9e37c192d07e964e5f6a66f6\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gymnasium-nordenham.de\\\/rueckkehr-in-den-wechselunterricht-verzoegert-sich#breadcrumb\"},\"inLanguage\":\"en-GB\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gymnasium-nordenham.de\\\/rueckkehr-in-den-wechselunterricht-verzoegert-sich\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/gymnasium-nordenham.de\\\/rueckkehr-in-den-wechselunterricht-verzoegert-sich#primaryimage\",\"url\":\"https:\\\/\\\/gymnasium-nordenham.de\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/spektrumani.gif\",\"contentUrl\":\"https:\\\/\\\/gymnasium-nordenham.de\\\/wp-content\\\/uploads\\\/2020\\\/04\\\/spektrumani.gif\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gymnasium-nordenham.de\\\/rueckkehr-in-den-wechselunterricht-verzoegert-sich#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/gymnasium-nordenham.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"R\u00fcckkehr in den Wechselunterricht verz\u00f6gert sich\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gymnasium-nordenham.de\\\/#website\",\"url\":\"https:\\\/\\\/gymnasium-nordenham.de\\\/\",\"name\":\"Gymnasium Nordenham\",\"description\":\"Miteinander, voneinander und f\u00fcreinander lernen\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gymnasium-nordenham.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gymnasium-nordenham.de\\\/#\\\/schema\\\/person\\\/1e6d811f9e37c192d07e964e5f6a66f6\",\"name\":\"Philipp Hetzel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/42e2436b39d12270c83fd566b415f5ed3c98f10987b9d69501eb6f31164ef4db?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/42e2436b39d12270c83fd566b415f5ed3c98f10987b9d69501eb6f31164ef4db?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/42e2436b39d12270c83fd566b415f5ed3c98f10987b9d69501eb6f31164ef4db?s=96&d=mm&r=g\",\"caption\":\"Philipp Hetzel\"},\"url\":\"https:\\\/\\\/gymnasium-nordenham.de\\\/en\\\/author\\\/adminp\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"R\u00fcckkehr in den Wechselunterricht verz\u00f6gert sich - Gymnasium Nordenham","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gymnasium-nordenham.de\/en\/rueckkehr-in-den-wechselunterricht-verzoegert-sich\/","og_locale":"en_GB","og_type":"article","og_title":"R\u00fcckkehr in den Wechselunterricht verz\u00f6gert sich - Gymnasium Nordenham","og_description":"Die Jahrg\u00e4nge 5 bis 7 sowie 12 m\u00fcssen vorerst noch Zuhause bleiben. Obwohl eigentlich ab dem 15. M\u00e4rz wieder das Wechselmodell f\u00fcr die oben genannten Jahrg\u00e4nge gelten sollte, muss der Pr\u00e4senzunterricht vorerst noch verschoben werden. Grund daf\u00fcr ist der aktuell &hellip; Continue reading &rarr;","og_url":"https:\/\/gymnasium-nordenham.de\/en\/rueckkehr-in-den-wechselunterricht-verzoegert-sich\/","og_site_name":"Gymnasium Nordenham","article_published_time":"2021-03-12T08:31:38+00:00","article_modified_time":"2025-06-25T12:09:05+00:00","og_image":[{"width":960,"height":2,"url":"https:\/\/gymnasium-nordenham.de\/wp-content\/uploads\/2020\/04\/spektrumani.gif","type":"image\/gif"}],"author":"Philipp Hetzel","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Philipp Hetzel","Estimated reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gymnasium-nordenham.de\/rueckkehr-in-den-wechselunterricht-verzoegert-sich#article","isPartOf":{"@id":"https:\/\/gymnasium-nordenham.de\/rueckkehr-in-den-wechselunterricht-verzoegert-sich"},"author":{"name":"Philipp Hetzel","@id":"https:\/\/gymnasium-nordenham.de\/#\/schema\/person\/1e6d811f9e37c192d07e964e5f6a66f6"},"headline":"R\u00fcckkehr in den Wechselunterricht verz\u00f6gert sich","datePublished":"2021-03-12T08:31:38+00:00","dateModified":"2025-06-25T12:09:05+00:00","mainEntityOfPage":{"@id":"https:\/\/gymnasium-nordenham.de\/rueckkehr-in-den-wechselunterricht-verzoegert-sich"},"wordCount":162,"commentCount":0,"image":{"@id":"https:\/\/gymnasium-nordenham.de\/rueckkehr-in-den-wechselunterricht-verzoegert-sich#primaryimage"},"thumbnailUrl":"https:\/\/gymnasium-nordenham.de\/wp-content\/uploads\/2020\/04\/spektrumani.gif","articleSection":["Corona","Schul-News","Schulausfall","Uncategorized"],"inLanguage":"en-GB","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/gymnasium-nordenham.de\/rueckkehr-in-den-wechselunterricht-verzoegert-sich#respond"]}]},{"@type":"WebPage","@id":"https:\/\/gymnasium-nordenham.de\/rueckkehr-in-den-wechselunterricht-verzoegert-sich","url":"https:\/\/gymnasium-nordenham.de\/rueckkehr-in-den-wechselunterricht-verzoegert-sich","name":"R\u00fcckkehr in den Wechselunterricht verz\u00f6gert sich - Gymnasium Nordenham","isPartOf":{"@id":"https:\/\/gymnasium-nordenham.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gymnasium-nordenham.de\/rueckkehr-in-den-wechselunterricht-verzoegert-sich#primaryimage"},"image":{"@id":"https:\/\/gymnasium-nordenham.de\/rueckkehr-in-den-wechselunterricht-verzoegert-sich#primaryimage"},"thumbnailUrl":"https:\/\/gymnasium-nordenham.de\/wp-content\/uploads\/2020\/04\/spektrumani.gif","datePublished":"2021-03-12T08:31:38+00:00","dateModified":"2025-06-25T12:09:05+00:00","author":{"@id":"https:\/\/gymnasium-nordenham.de\/#\/schema\/person\/1e6d811f9e37c192d07e964e5f6a66f6"},"breadcrumb":{"@id":"https:\/\/gymnasium-nordenham.de\/rueckkehr-in-den-wechselunterricht-verzoegert-sich#breadcrumb"},"inLanguage":"en-GB","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gymnasium-nordenham.de\/rueckkehr-in-den-wechselunterricht-verzoegert-sich"]}]},{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/gymnasium-nordenham.de\/rueckkehr-in-den-wechselunterricht-verzoegert-sich#primaryimage","url":"https:\/\/gymnasium-nordenham.de\/wp-content\/uploads\/2020\/04\/spektrumani.gif","contentUrl":"https:\/\/gymnasium-nordenham.de\/wp-content\/uploads\/2020\/04\/spektrumani.gif"},{"@type":"BreadcrumbList","@id":"https:\/\/gymnasium-nordenham.de\/rueckkehr-in-den-wechselunterricht-verzoegert-sich#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/gymnasium-nordenham.de\/"},{"@type":"ListItem","position":2,"name":"R\u00fcckkehr in den Wechselunterricht verz\u00f6gert sich"}]},{"@type":"WebSite","@id":"https:\/\/gymnasium-nordenham.de\/#website","url":"https:\/\/gymnasium-nordenham.de\/","name":"Gymnasium Nordenham","description":"Miteinander, voneinander und f\u00fcreinander lernen","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gymnasium-nordenham.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Person","@id":"https:\/\/gymnasium-nordenham.de\/#\/schema\/person\/1e6d811f9e37c192d07e964e5f6a66f6","name":"Philipp Hetzel","image":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/secure.gravatar.com\/avatar\/42e2436b39d12270c83fd566b415f5ed3c98f10987b9d69501eb6f31164ef4db?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/42e2436b39d12270c83fd566b415f5ed3c98f10987b9d69501eb6f31164ef4db?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/42e2436b39d12270c83fd566b415f5ed3c98f10987b9d69501eb6f31164ef4db?s=96&d=mm&r=g","caption":"Philipp Hetzel"},"url":"https:\/\/gymnasium-nordenham.de\/en\/author\/adminp"}]}},"_links":{"self":[{"href":"https:\/\/gymnasium-nordenham.de\/en\/wp-json\/wp\/v2\/posts\/6252","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gymnasium-nordenham.de\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gymnasium-nordenham.de\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gymnasium-nordenham.de\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/gymnasium-nordenham.de\/en\/wp-json\/wp\/v2\/comments?post=6252"}],"version-history":[{"count":1,"href":"https:\/\/gymnasium-nordenham.de\/en\/wp-json\/wp\/v2\/posts\/6252\/revisions"}],"predecessor-version":[{"id":13661,"href":"https:\/\/gymnasium-nordenham.de\/en\/wp-json\/wp\/v2\/posts\/6252\/revisions\/13661"}],"wp:attachment":[{"href":"https:\/\/gymnasium-nordenham.de\/en\/wp-json\/wp\/v2\/media?parent=6252"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gymnasium-nordenham.de\/en\/wp-json\/wp\/v2\/categories?post=6252"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gymnasium-nordenham.de\/en\/wp-json\/wp\/v2\/tags?post=6252"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}